{"id":3190,"date":"2018-09-05T16:14:35","date_gmt":"2018-09-05T16:14:35","guid":{"rendered":"https:\/\/2018.rome.wordcamp.org\/?p=3190"},"modified":"2018-09-05T16:14:39","modified_gmt":"2018-09-05T16:14:39","slug":"marketing-design-e-community-ultimo-gruppo-di-speaker","status":"publish","type":"post","link":"https:\/\/rome.wordcamp.org\/2018\/marketing-design-e-community-ultimo-gruppo-di-speaker\/","title":{"rendered":"Marketing, design e community: ultimo gruppo di speaker"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>Italian<\/em><em> text is followed by English<\/em><\/p>\n\n\n\n<p class=\"ita wp-block-paragraph\">Ultimi di certo non per importanza, vi presento oggi i restanti quattro speaker che parteciperanno al WordCamp Roma che avr\u00e0 luogo tra pochi giorni.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eh gi\u00e0, ne mancano solo 10 (di giorni), lo avete acquistato il biglietto? \ud83d\ude00<br \/>Se non fosse cos\u00ec potete farlo subito <a href=\"https:\/\/2018.rome.wordcamp.org\/tickets\/\">qui!<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/2018.rome.wordcamp.org\/files\/2018\/09\/speaker-batch-4.png\" alt=\"\" class=\"wp-image-3241\" srcset=\"https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/speaker-batch-4.png 1024w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/speaker-batch-4-300x150.png 300w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/speaker-batch-4-768x384.png 768w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/speaker-batch-4-500x250.png 500w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/2018.rome.wordcamp.org\/speaker\/alessandro-frangioni\/\">Alessandro Frangioni<\/a><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Alessandro Frangioni, fondatore di Roads Agency, \u00e8 consulente e digital strategist specializzato in Google Ads, Facebook Ads, SEO e Email Marketing. \u00c8 relatore a molti eventi sul web marketing in Italia, e si occupa di formazione per accademie e agenzie formative.<br \/>Fra gli eventi pi\u00f9 importanti, Alessandro partecipa al Web Marketing Festival, Social Media Strategies, AdWorld Experience, SMAU, Inbound Strategies, La Settimana della Formazione, Startup Saturday, Tiscali Open Campus con Isole in Rete. <br \/>\u00c8 anche autore della guida completa all&#8217;Email Marketing con MailChimp.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/2018.rome.wordcamp.org\/files\/2018\/09\/alessandro-frangioni.png\" alt=\"\" class=\"wp-image-3224\" srcset=\"https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/alessandro-frangioni.png 1024w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/alessandro-frangioni-300x150.png 300w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/alessandro-frangioni-768x384.png 768w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/alessandro-frangioni-500x250.png 500w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Talk:  <br \/><a href=\"https:\/\/2018.rome.wordcamp.org\/session\/digital-strategies-a-b-test-e-landing-page-in-wordpress-con-instapage-e-google-optimize-ita\/\"><strong>Digital Strategies: A\/B Test e Landing Page in WordPress con Instapage e Google Optimize<\/strong><\/a> (ITA)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Creare una strategia di web marketing sfruttando WordPress come base di tutto e integrando tool di A\/B Test come Google Optimize in grado di fare varianti a\/b e testi multivariati con pochi passaggi, tutti con interfaccia grafica. In pi\u00f9 si mostrer\u00e0 come integrare Instapage come piattaforma per le landing, indispensabili per le strategie di digital advertising e SEO.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/2018.rome.wordcamp.org\/speaker\/matteo-pogliani\/\">Matteo Pogliani<\/a><br \/><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Matteo \u00e8 Digital Strategist in Open-Box e nel gruppo Comunicatica. Dove si occupa di dar vita a strategie in grado di sostenere i percorsi di enti e aziende nel variegato mondo digitale. <br \/>Scrive per diversi blog a livello nazionale  (Ninja Marketing, Semrush, 6Sicuro) ed \u00e8 docente per diversi corsi universitari e, online, per Ninja Academy. <br \/> \u00c8 speaker per numerosi eventi sul mondo digitale. <br \/>Ha scritto  \u201cInfluencer marketing: valorizza le relazioni e dai voce al tuo brand\u201d edito da Dario Flaccovio Editore, primo libro italiano sul tema. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/2018.rome.wordcamp.org\/files\/2018\/09\/matteo-pogliani.png\" alt=\"\" class=\"wp-image-3225\" srcset=\"https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/matteo-pogliani.png 1024w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/matteo-pogliani-300x150.png 300w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/matteo-pogliani-768x384.png 768w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/matteo-pogliani-500x250.png 500w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Talk: <a href=\"https:\/\/2018.rome.wordcamp.org\/session\/linfluencer-marketing-non-funziona-forse-ita\/\">L&#8217;Influencer Marketing non funziona (forse)<\/a> (ITA) <br \/><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;influencer marketing oltre le mode (e il sentito dire). Prassi e consigli per creare sinergie di valore con gli influencer e renderle strumento strategico e performante per i brand.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/2018.rome.wordcamp.org\/speaker\/laura-sacco\/\">Laura Sacco<\/a><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Educatrice professionale, sociologa, formatrice e consulente di impresa nonprofit, dopo una carriera nel sociale ho deciso di trasformare la mia passione per la tecnologia, il digitale e le \u201ccose di internet\u201d in lavoro e oggi sono Mentore Digitale\u00ae e Support Engineer a Yoast.<br \/>Le piace aiutare le persone ad acquisire nuove conoscenze informatiche e a padroneggiare i dispositivi elettronici in modo da rendere pi\u00f9 veloci ed efficienti alcuni compiti quotidiani.<br \/>Appassionata di WordPress, contribuisce alla crescita della sua Community italiana e internazionale partecipando in modo volontario e attivo al team Polyglots come GTE per l\u2019Italia e al gruppo degli organizzatori del WordPress Meetup\/WordCamp di Torino.<br \/>Crede che le fiabe siano vere e che la realt\u00e0 dipenda dalla prospettiva.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/2018.rome.wordcamp.org\/files\/2018\/09\/laura-sacco.png\" alt=\"\" class=\"wp-image-3226\" srcset=\"https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/laura-sacco.png 1024w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/laura-sacco-300x150.png 300w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/laura-sacco-768x384.png 768w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/laura-sacco-500x250.png 500w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Talk: <a href=\"https:\/\/2018.rome.wordcamp.org\/session\/tradurre-bene-localizzare-meglio-ita\/\">Tradurre bene, localizzare meglio<\/a> (ITA)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Oltre 1400 persone traducono i progetti di WordPress. Perch\u00e9 il risultato non risulti una babele occorre che tutti seguano le stesse regole. Il talk spiega il sistema di traduzione attivo nei polyglots italiani di WordPress, le regole che la community si \u00e8 data, le linee guida, le buone prassi.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/2018.rome.wordcamp.org\/speaker\/raffaella-isidori\/\">Raffaella Isidori<\/a><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Direttore creativo, coach e consulente, si occupo di design e di comunicazione da oltre 30 anni. Nata a New York, \u00e8 cresciuta tra la campagna umbra e i grattacieli della Grande Mela. Dopo un passato di agenzie (McCann, NY; Armando Testa e Barabino &amp; Partners, Milano) ha scelto &#8211; 20 anni fa &#8211; di lavorare direttamente con i clienti, fondando il suo studio di consulenza: Thesign.it. Oggi crea brand e disegna la comunicazione per aziende in tutto il mondo. E poi studia, insegna, fa foto, scrive e traduce. Curiosa come un gatto e appassionata di diversit\u00e0, colleziona libri, font e oli essenziali; vive e lavore circondata da flora e fauna nell&#8217;hinterland milanese, e coltiva sogni e mindfulness. <br \/>Online, \u00e8 @zetaraffix.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/2018.rome.wordcamp.org\/files\/2018\/09\/raffaella-isidori.png\" alt=\"\" class=\"wp-image-3227\" srcset=\"https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/raffaella-isidori.png 1024w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/raffaella-isidori-300x150.png 300w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/raffaella-isidori-768x384.png 768w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/raffaella-isidori-500x250.png 500w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Talk: <a href=\"https:\/\/2018.rome.wordcamp.org\/session\/the-7-pillars-of-design-and-how-they-apply-to-your-life-eng\/\">The 7 pillars of design (and how they apply to your life)<\/a> (ENG)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Gerarchia, Equilibrio, Spazio, Colore&#8230; ci sono principi che governano la progettazione che assicurano che il risultato sia di successo e di qualit\u00e0. Questi stessi principi possono estendersi nelle nostre vite quotidiane, per offrire l&#8217;opportunit\u00e0 di vite con pi\u00f9 significato, e maggior qualit\u00e0. <br \/>Questo talk esplora ed illustra questi principi del design (qualificandosi quindi come un talk sul design) e al contempo offre lo spazio per riflettere sull&#8217;importanza di progettare per noi stessi vite complete e dense di significato.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Non perdere l&#8217;occasione di essere dei nostri!<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Acquista <a href=\"https:\/\/2018.rome.wordcamp.org\/tickets\/\">qui <\/a>il tuo biglietto!<\/p>\n\n\n\n<p class=\"eng wp-block-paragraph\">Last of course not for their importance, I&#8217;m happy to introduce you the remaining four speaker who will participate to WordCamp Rome in few days.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Oh yes, there are only 10 (days) missing, have you already got your ticket? \ud83d\ude00<br \/>If not buy it <a href=\"https:\/\/2018.rome.wordcamp.org\/tickets\/\">here!<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/2018.rome.wordcamp.org\/speaker\/alessandro-frangioni\/\">Alessandro Frangioni<\/a><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Founder of Roads Agency, digital strategist and consultant, particularly focused on Google Ads, Facebook Ads, SEO and Mail Marketing. <br \/>He is speaker at several marketing events around Italy and trainer for some academies and education agencies. <br \/>Among the most important events, Alessandro takes part to Web Marketing Festival, Social Media Strategies, AdWorld Experience, SMAU, Inbound Strategies, La Settimana della Formazione, Startup Saturday, Tiscali Open Campus with Isole in Rete. <br \/>He&#8217;s also author of the complete guide of Email Marketing with MailChimp. <br \/><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/2018.rome.wordcamp.org\/files\/2018\/09\/alessandro-frangioni.png\" alt=\"\" class=\"wp-image-3224\" srcset=\"https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/alessandro-frangioni.png 1024w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/alessandro-frangioni-300x150.png 300w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/alessandro-frangioni-768x384.png 768w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/alessandro-frangioni-500x250.png 500w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Talk:  <br \/><a href=\"https:\/\/2018.rome.wordcamp.org\/session\/digital-strategies-a-b-test-e-landing-page-in-wordpress-con-instapage-e-google-optimize-ita\/\"><strong>Digital Strategies: A\/B Test e Landing Page in WordPress con Instapage e Google Optimize<\/strong><\/a> (ITA)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Create a web marketing strategy using WordPress as starting point and then integrate A\/B testing tools like Google Optimize, that perform A\/B variants and multivariate texts, through graphical interfaces. <br \/>In addition, there will be a demonstration about how to integrate Instapage as platform for landing pages, as an essential part in digital advertising and SEO.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/2018.rome.wordcamp.org\/speaker\/matteo-pogliani\/\">Matteo Pogliani<\/a><br \/><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Matteo is a digital strategist in Open-Box and in Comunicatica group. He creates strategies that can lead companies and authorities in the polyhedric digital world. <br \/>He writes for several Italian blogs (Ninja Marketing, Semrush, 6Sicuro) and teaches in several university courses and, online, for Ninja Academy. <br \/>He is a speaker in many events about the digital world. <br \/>He wrote \u201cInfluencer marketing: valorizza le relazioni e dai voce al tuo brand\u201d published by Dario Flaccovio Editore, first Italian book about this topic.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/2018.rome.wordcamp.org\/files\/2018\/09\/matteo-pogliani.png\" alt=\"\" class=\"wp-image-3225\" srcset=\"https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/matteo-pogliani.png 1024w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/matteo-pogliani-300x150.png 300w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/matteo-pogliani-768x384.png 768w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/matteo-pogliani-500x250.png 500w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Talk: <a href=\"https:\/\/2018.rome.wordcamp.org\/session\/linfluencer-marketing-non-funziona-forse-ita\/\">L&#8217;Influencer Marketing non funziona (forse)<\/a> (ITA) <br \/><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">The influencer Marketing beyond trends (and rumors). Best pratices and advices to create valuable synergies with the influencers and make them a performing and strategic tool for brands.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/2018.rome.wordcamp.org\/speaker\/laura-sacco\/\">Laura Sacco<\/a><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Talk: <a href=\"https:\/\/2018.rome.wordcamp.org\/session\/the-7-pillars-of-design-and-how-they-apply-to-your-life-eng\/\">The 7 pillars of design (and how they apply to your life)<\/a> (ENG)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Professional social educator, trainer and a consultant for nonprofit organizations, after many years in the social field in 2015 she decided to transform her passion for technology, digital and all the things Internet into a full-time job. And now she&#8217;s a Digital Mentor \u2013 she helps people improve their skills with digital devices, social network, and build their WordPress blogs\/sites. She also work as a Support Engineer at Yoast.<br \/>WP lover, she&#8217;s involved in the Italian WordPress Community and she&#8217;s one of the GTEs for the Italian Polyglots teams. She&#8217;s one of the Turin WordPress Meetup organizers.<br \/>She loves reading, swimming, cooking and fiddling around on her PC (not necessarily in this order\u2026 and neither one thing at a time \ud83d\ude09 ).<br \/>She believes that fairy tales are true, and truth depends on the perspective.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/2018.rome.wordcamp.org\/files\/2018\/09\/laura-sacco-1.png\" alt=\"\" class=\"wp-image-3228\" srcset=\"https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/laura-sacco-1.png 1024w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/laura-sacco-1-300x150.png 300w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/laura-sacco-1-768x384.png 768w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/laura-sacco-1-500x250.png 500w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Talk: <a href=\"https:\/\/2018.rome.wordcamp.org\/session\/tradurre-bene-localizzare-meglio-ita\/\">Tradurre bene, localizzare meglio<\/a> (ITA)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Over 1400 people translate WordPress projects. To have a result that doesn&#8217;t look like a Babel, everyone must follow same rules.<br \/> This talk explains the active translation system in the Italian WordPress polyglots, the rules that the community has given itself, guidelines and good practices.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/2018.rome.wordcamp.org\/speaker\/raffaella-isidori\/\">Raffaella Isidori<\/a><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Creative director, coach and consultant, she deals with design and communication for over 30 years. Born in New York, she grew up between the Umbrian countryside and  Big Apple&#8217;s skyscrapers. <br \/>After a past of agencies (McCann, NY, Armando Testa and Barabino &amp; Partners, Milan) she chose &#8211; 20 years ago &#8211; to work directly with clients, founding her consulting firm: Thesign.it. <br \/>Today she creates brand and design communication for companies all over the world. And then she studies, she teaches, she takes pictures, she writes and translates. <br \/>Curious as a cat and passionate about diversity, she collects books, fonts and essential oils; she lives and works surrounded by flora and fauna in the Milanese hinterland, and she cultivates dreams and mindfulness. <br \/>Online, she is @zetaraffix.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/2018.rome.wordcamp.org\/files\/2018\/09\/raffaella-isidori-1.png\" alt=\"\" class=\"wp-image-3229\" srcset=\"https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/raffaella-isidori-1.png 1024w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/raffaella-isidori-1-300x150.png 300w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/raffaella-isidori-1-768x384.png 768w, https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/raffaella-isidori-1-500x250.png 500w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Talk: <a href=\"https:\/\/2018.rome.wordcamp.org\/session\/the-7-pillars-of-design-and-how-they-apply-to-your-life-eng\/\">The 7 pillars of design (and how they apply to your life)<\/a> (ENG)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Hierarchy, balance, space, colour&#8230; There are some principles that rule design and make sure to have a successful and quality result. Same principles can be applied to one everyday life, to have the opportunity of living meaningful and high-quality lives. <br \/>This talk explores those principles (defining itself as a design talk) and at the very same time gives the chance to think about the importance of design for ourselves complete and worthwhile existences.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Don&#8217;t miss the chance of join us!<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Grab your ticket <a href=\"https:\/\/2018.rome.wordcamp.org\/tickets\/\">here<\/a>! <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Italian text is followed by English Ultimi di certo non per importanza, vi presento oggi i restanti quattro speaker che parteciperanno al WordCamp Roma che avr\u00e0 luogo tra pochi giorni. Eh gi\u00e0, ne mancano solo 10 (di giorni), lo avete acquistato il biglietto? \ud83d\ude00Se non fosse cos\u00ec potete farlo subito qui! Alessandro Frangioni Alessandro Frangioni, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/rome.wordcamp.org\/2018\/marketing-design-e-community-ultimo-gruppo-di-speaker\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Marketing, design e community: ultimo gruppo di speaker&#8221;<\/span><\/a><\/p>\n","protected":false},"author":15884982,"featured_media":3241,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[],"class_list":["post-3190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheK5y-Ps","jetpack_featured_media_url":"https:\/\/rome.wordcamp.org\/2018\/files\/2018\/09\/speaker-batch-4.png","_links":{"self":[{"href":"https:\/\/rome.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/3190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rome.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rome.wordcamp.org\/2018\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rome.wordcamp.org\/2018\/wp-json\/wp\/v2\/users\/15884982"}],"replies":[{"embeddable":true,"href":"https:\/\/rome.wordcamp.org\/2018\/wp-json\/wp\/v2\/comments?post=3190"}],"version-history":[{"count":5,"href":"https:\/\/rome.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/3190\/revisions"}],"predecessor-version":[{"id":3255,"href":"https:\/\/rome.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/3190\/revisions\/3255"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rome.wordcamp.org\/2018\/wp-json\/wp\/v2\/media\/3241"}],"wp:attachment":[{"href":"https:\/\/rome.wordcamp.org\/2018\/wp-json\/wp\/v2\/media?parent=3190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rome.wordcamp.org\/2018\/wp-json\/wp\/v2\/categories?post=3190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rome.wordcamp.org\/2018\/wp-json\/wp\/v2\/tags?post=3190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}